{"id":36040,"date":"2025-04-09T15:38:57","date_gmt":"2025-04-09T20:38:57","guid":{"rendered":"https:\/\/spawellnessmexico.com\/?p=36040"},"modified":"2025-04-09T15:40:14","modified_gmt":"2025-04-09T20:40:14","slug":"2-foro-futuro-cabo-del-este","status":"publish","type":"post","link":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/","title":{"rendered":"2\u00b0 Foro Futuro Cabo del Este"},"content":{"rendered":"<p>El 2\u00ba Foro Futuro Cabo del Este se celebr\u00f3 en el Cabo del Este de Baja California, M\u00e9xico. Este evento de 2 d\u00edas se enfoc\u00f3 en el tema \u2018Transici\u00f3n hacia una regi\u00f3n regenerativa y resiliente\u2019 y reuni\u00f3 a m\u00e1s de 200 asistentes, incluyendo funcionarios gubernamentales, desarrolladores, arquitectos, conservacionistas de agua, bi\u00f3logos marinos, ganaderos, e inversionistas, para explorar c\u00f3mo desarrollar mejor los destinos de bienestar a trav\u00e9s de sistemas regenerativos y gesti\u00f3n del agua.<\/p>\n<p>Dos de los principales presentadores de bienestar son l\u00edderes de las propiedades m\u00e1s regenerativas del mundo, ubicadas en M\u00e9xico: Sarah Livia Brightwood, presidenta de Rancho La Puerta, en Tecate, Baja California Norte, y David Levanthal, fundador de Playa Viva y Regenerative Travel, situados al sur de Zihuatanejo, en la costa del Pac\u00edfico de Guerrero.<\/p>\n<p>Otra inspiradora oradora fue Stephanie Brendl, Directora Ejecutiva de SIERRA A MAR, una iniciativa enfocada en la regeneraci\u00f3n de una zona de 100 km de Costa Alegre, en Jalisco. Xala, una de las propiedades de esta \u00e1rea, formar\u00e1 parte de Six Senses y cuenta con la participaci\u00f3n del actor y activista Richard Gere.<\/p>\n<p>Las principales conclusiones de estos ponentes fueron la responsabilidad compartida de:<br \/>\n\u2022 Proteger y mejorar los ecosistemas y las comunidades<br \/>\n\u2022 Promover y crear biodiversidad<br \/>\n\u2022 Establecer una fundaci\u00f3n para el impacto social a trav\u00e9s de la educaci\u00f3n<br \/>\n\u2022 Utilizar sistemas m\u00e1s limpios de energ\u00eda, agua y aguas residuales<br \/>\n\u2022 Crear experiencias de bienestar transformadoras<br \/>\n\u2022 Crear un legado viviente<\/p>\n<p>Uno de los mensajes principales es que la industria del bienestar habla sobre sostenibilidad cuando deber\u00eda contemplar un enfoque regenerativo, m\u00e1s hol\u00edstico. Spas y centros de bienestar no \u2018sustentan\u2019 a sus hu\u00e9spedes, sino que los rejuvenecen y mejoran su sensaci\u00f3n de bienestar, por lo que las comunidades y ecosistemas que rodean a estos establecimientos tambi\u00e9n deber\u00edan regenerarse.<\/p>\n<p><a href=\"https:\/\/www.futurocabodeleste.com\">www.futurocabodeleste.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Por Amy McDonald, CEO<br \/>\nUnder a Tree<br \/>\n<a href=\"https:\/\/www.underatree.com\">www.underatree.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 2\u00ba Foro Futuro Cabo del Este se celebr\u00f3 en el Cabo del Este de Baja California, M\u00e9xico. Este evento de 2 d\u00edas se enfoc\u00f3 en el tema \u2018Transici\u00f3n hacia una regi\u00f3n regenerativa y resiliente\u2019 y reuni\u00f3 a m\u00e1s de 200 asistentes, incluyendo funcionarios gubernamentales, desarrolladores, arquitectos, conservacionistas de agua, bi\u00f3logos marinos, ganaderos, e inversionistas, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":36038,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2190],"tags":[4816,4817,4818,4827,2206,4819,3212,4828,4830,4820,4821,4822,4829],"class_list":["post-36040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","tag-amy-mcdonald-es","tag-david-levanthal-es","tag-east-cape-futures-forum-es","tag-foro-futuro-cabo-del-este-es","tag-mexico-es","tag-playa-viva-es","tag-rancho-la-puerta-es","tag-regenerative-travel-es","tag-richard-gere-es","tag-sarah-livia-brightwood-es","tag-sierra-a-mar-es","tag-under-a-tree-es","tag-xala-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2\u00b0 Foro Futuro Cabo del Este<\/title>\n<meta name=\"description\" content=\"l 2\u00ba Foro Futuro Cabo del Este se enfoc\u00f3 en el tema \u2018Transici\u00f3n hacia una regi\u00f3n regenerativa y resiliente\u2019.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2\u00b0 Foro Futuro Cabo del Este\" \/>\n<meta property=\"og:description\" content=\"l 2\u00ba Foro Futuro Cabo del Este se enfoc\u00f3 en el tema \u2018Transici\u00f3n hacia una regi\u00f3n regenerativa y resiliente\u2019.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/\" \/>\n<meta property=\"og:site_name\" content=\"Spa &amp; Wellness MexiCaribe\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-09T20:38:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-09T20:40:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/04\/Foro-Futuro-Cabo-del-Este.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"766\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Fabiola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabiola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/36040\\\/2-foro-futuro-cabo-del-este\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/36040\\\/2-foro-futuro-cabo-del-este\\\/\"},\"author\":{\"name\":\"Fabiola\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#\\\/schema\\\/person\\\/46d1b27e1e82f535658ced6aa4ebae47\"},\"headline\":\"2\u00b0 Foro Futuro Cabo del Este\",\"datePublished\":\"2025-04-09T20:38:57+00:00\",\"dateModified\":\"2025-04-09T20:40:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/36040\\\/2-foro-futuro-cabo-del-este\\\/\"},\"wordCount\":333,\"publisher\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/36040\\\/2-foro-futuro-cabo-del-este\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Foro-Futuro-Cabo-del-Este.webp\",\"keywords\":[\"amy mcdonald\",\"David Levanthal\",\"east cape futures forum\",\"foro futuro cabo del este\",\"mexico\",\"playa viva\",\"rancho la puerta\",\"regenerative travel\",\"richard gere\",\"Sarah Livia Brightwood\",\"sierra a mar\",\"under a tree\",\"xala\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/36040\\\/2-foro-futuro-cabo-del-este\\\/\",\"url\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/36040\\\/2-foro-futuro-cabo-del-este\\\/\",\"name\":\"2\u00b0 Foro Futuro Cabo del Este\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/36040\\\/2-foro-futuro-cabo-del-este\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/36040\\\/2-foro-futuro-cabo-del-este\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Foro-Futuro-Cabo-del-Este.webp\",\"datePublished\":\"2025-04-09T20:38:57+00:00\",\"dateModified\":\"2025-04-09T20:40:14+00:00\",\"description\":\"l 2\u00ba Foro Futuro Cabo del Este se enfoc\u00f3 en el tema \u2018Transici\u00f3n hacia una regi\u00f3n regenerativa y resiliente\u2019.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/36040\\\/2-foro-futuro-cabo-del-este\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/36040\\\/2-foro-futuro-cabo-del-este\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/36040\\\/2-foro-futuro-cabo-del-este\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Foro-Futuro-Cabo-del-Este.webp\",\"contentUrl\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Foro-Futuro-Cabo-del-Este.webp\",\"width\":766,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/36040\\\/2-foro-futuro-cabo-del-este\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2\u00b0 Foro Futuro Cabo del Este\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/\",\"name\":\"Spa &amp; Wellness MexiCaribe\",\"description\":\"The Magazine for Spa &amp; Wellness in Mexico, Caribbean &amp; Latin America\",\"publisher\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#organization\",\"name\":\"Spa &amp; Wellness MexiCaribe\",\"url\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cropped-LOGO-SWMC.png\",\"contentUrl\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cropped-LOGO-SWMC.png\",\"width\":1117,\"height\":230,\"caption\":\"Spa &amp; Wellness MexiCaribe\"},\"image\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#\\\/schema\\\/person\\\/46d1b27e1e82f535658ced6aa4ebae47\",\"name\":\"Fabiola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/litespeed\\\/avatar\\\/9aea9838a8f24d3e63e9f38aa9599ebd.jpg?ver=1778538585&d=https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/plugins\\\/userswp\\\/assets\\\/images\\\/no_profile.png\",\"url\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/litespeed\\\/avatar\\\/9aea9838a8f24d3e63e9f38aa9599ebd.jpg?ver=1778538585&d=https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/plugins\\\/userswp\\\/assets\\\/images\\\/no_profile.png\",\"contentUrl\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/litespeed\\\/avatar\\\/9aea9838a8f24d3e63e9f38aa9599ebd.jpg?ver=1778538585&d=https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/plugins\\\/userswp\\\/assets\\\/images\\\/no_profile.png\",\"caption\":\"Fabiola\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2\u00b0 Foro Futuro Cabo del Este","description":"l 2\u00ba Foro Futuro Cabo del Este se enfoc\u00f3 en el tema \u2018Transici\u00f3n hacia una regi\u00f3n regenerativa y resiliente\u2019.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/","og_locale":"es_ES","og_type":"article","og_title":"2\u00b0 Foro Futuro Cabo del Este","og_description":"l 2\u00ba Foro Futuro Cabo del Este se enfoc\u00f3 en el tema \u2018Transici\u00f3n hacia una regi\u00f3n regenerativa y resiliente\u2019.","og_url":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/","og_site_name":"Spa &amp; Wellness MexiCaribe","article_published_time":"2025-04-09T20:38:57+00:00","article_modified_time":"2025-04-09T20:40:14+00:00","og_image":[{"width":766,"height":320,"url":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/04\/Foro-Futuro-Cabo-del-Este.webp","type":"image\/webp"}],"author":"Fabiola","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fabiola","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/#article","isPartOf":{"@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/"},"author":{"name":"Fabiola","@id":"https:\/\/spawellnessmexico.com\/es\/#\/schema\/person\/46d1b27e1e82f535658ced6aa4ebae47"},"headline":"2\u00b0 Foro Futuro Cabo del Este","datePublished":"2025-04-09T20:38:57+00:00","dateModified":"2025-04-09T20:40:14+00:00","mainEntityOfPage":{"@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/"},"wordCount":333,"publisher":{"@id":"https:\/\/spawellnessmexico.com\/es\/#organization"},"image":{"@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/#primaryimage"},"thumbnailUrl":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/04\/Foro-Futuro-Cabo-del-Este.webp","keywords":["amy mcdonald","David Levanthal","east cape futures forum","foro futuro cabo del este","mexico","playa viva","rancho la puerta","regenerative travel","richard gere","Sarah Livia Brightwood","sierra a mar","under a tree","xala"],"articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/","url":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/","name":"2\u00b0 Foro Futuro Cabo del Este","isPartOf":{"@id":"https:\/\/spawellnessmexico.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/#primaryimage"},"image":{"@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/#primaryimage"},"thumbnailUrl":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/04\/Foro-Futuro-Cabo-del-Este.webp","datePublished":"2025-04-09T20:38:57+00:00","dateModified":"2025-04-09T20:40:14+00:00","description":"l 2\u00ba Foro Futuro Cabo del Este se enfoc\u00f3 en el tema \u2018Transici\u00f3n hacia una regi\u00f3n regenerativa y resiliente\u2019.","breadcrumb":{"@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/#primaryimage","url":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/04\/Foro-Futuro-Cabo-del-Este.webp","contentUrl":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/04\/Foro-Futuro-Cabo-del-Este.webp","width":766,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/36040\/2-foro-futuro-cabo-del-este\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spawellnessmexico.com\/es\/"},{"@type":"ListItem","position":2,"name":"2\u00b0 Foro Futuro Cabo del Este"}]},{"@type":"WebSite","@id":"https:\/\/spawellnessmexico.com\/es\/#website","url":"https:\/\/spawellnessmexico.com\/es\/","name":"Spa &amp; Wellness MexiCaribe","description":"The Magazine for Spa &amp; Wellness in Mexico, Caribbean &amp; Latin America","publisher":{"@id":"https:\/\/spawellnessmexico.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spawellnessmexico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/spawellnessmexico.com\/es\/#organization","name":"Spa &amp; Wellness MexiCaribe","url":"https:\/\/spawellnessmexico.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spawellnessmexico.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2021\/02\/cropped-LOGO-SWMC.png","contentUrl":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2021\/02\/cropped-LOGO-SWMC.png","width":1117,"height":230,"caption":"Spa &amp; Wellness MexiCaribe"},"image":{"@id":"https:\/\/spawellnessmexico.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/spawellnessmexico.com\/es\/#\/schema\/person\/46d1b27e1e82f535658ced6aa4ebae47","name":"Fabiola","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spawellnessmexico.com\/wp-content\/litespeed\/avatar\/9aea9838a8f24d3e63e9f38aa9599ebd.jpg?ver=1778538585&d=https:\/\/spawellnessmexico.com\/wp-content\/plugins\/userswp\/assets\/images\/no_profile.png","url":"https:\/\/spawellnessmexico.com\/wp-content\/litespeed\/avatar\/9aea9838a8f24d3e63e9f38aa9599ebd.jpg?ver=1778538585&d=https:\/\/spawellnessmexico.com\/wp-content\/plugins\/userswp\/assets\/images\/no_profile.png","contentUrl":"https:\/\/spawellnessmexico.com\/wp-content\/litespeed\/avatar\/9aea9838a8f24d3e63e9f38aa9599ebd.jpg?ver=1778538585&d=https:\/\/spawellnessmexico.com\/wp-content\/plugins\/userswp\/assets\/images\/no_profile.png","caption":"Fabiola"}}]}},"_links":{"self":[{"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/posts\/36040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/comments?post=36040"}],"version-history":[{"count":1,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/posts\/36040\/revisions"}],"predecessor-version":[{"id":36042,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/posts\/36040\/revisions\/36042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/media\/36038"}],"wp:attachment":[{"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/media?parent=36040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/categories?post=36040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/tags?post=36040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}