{"id":34973,"date":"2025-01-16T13:06:54","date_gmt":"2025-01-16T18:06:54","guid":{"rendered":"https:\/\/spawellnessmexico.com\/?p=34973"},"modified":"2025-01-22T09:52:18","modified_gmt":"2025-01-22T14:52:18","slug":"experiencia-spa-banyan-tree-mayakoba","status":"publish","type":"post","link":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/","title":{"rendered":"Experiencia Spa: Banyan Tree Spa, Banyan Tree Mayakoba, Riviera Maya, M\u00e9xico"},"content":{"rendered":"<p>Enclavado en los exuberantes paisajes de la Riviera Maya, Banyan Tree Mayakoba ofrece un escape sereno que enfatiza relajaci\u00f3n y rejuvenecimiento, con el bienestar entretejido en las muchas actividades alrededor del resort. Con un excelente nivel de servicio en la propiedad y comida exquisita con extraordinaria atenci\u00f3n al detalle, los hu\u00e9spedes pueden asegurarse de que se satisfar\u00e1n sus requisitos diet\u00e9ticos y necesidades de servicio durante su estancia.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-35292\" src=\"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/01\/Banyan-Tree-Mayakoba-hydro.webp\" alt=\"\" width=\"450\" height=\"300\" srcset=\"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/01\/Banyan-Tree-Mayakoba-hydro.webp 450w, https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/01\/Banyan-Tree-Mayakoba-hydro-300x200.webp 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>El Banyan Tree Spa trae un toque asi\u00e1tico a M\u00e9xico, con muchos terapeutas procedentes de Tailandia e Indonesia, trabajando junto a terapeutas mexicanos para ofrecer una gama de experiencias de bienestar incorporando t\u00e9cnicas de todo el mundo. El spa ofrece hidroterapia personalizada con su experiencia \u2018Rainforest Indulgence\u2019. Comienza con el camino de piedras de la ducha de lluvia, alternando duchas de agua caliente y fr\u00eda, refrescando el cuerpo mientras estimula los pies. Procede a la sala de vapor y apl\u00edcate mascarillas corporales y faciales antes de enjuagarte y refrescarte con hielo picado disponible en la fuente de hielo. Contin\u00faa al sauna seco y despu\u00e9s rel\u00e1jate en la piscina sensorial con una variedad de chorros para el cuerpo y jacuzzis calientes. El spa tambi\u00e9n organiza eventos de bienestar como su viaje de sanaci\u00f3n con sonido que se celebra en la zona de hidroterapia. Se utilizan correas de flotaci\u00f3n para que los hu\u00e9spedes floten ingr\u00e1vidos en el agua, sintiendo las intensas vibraciones de los cuencos tibetanos para una experiencia sonora trascendente.<\/p>\n<p>El tratamiento Tradiciones tailandesas, un viaje hol\u00edstico para liberar la tensi\u00f3n muscular y revitalizar el cuerpo, comienza con un refrescante ba\u00f1o de pies, que marca el tono de la experiencia. Tras el ritual de pies, el hu\u00e9sped es guiado a la sala h\u00fameda para una exfoliaci\u00f3n corporal con jengibre. Las propiedades tonificantes del jengibre revitalizan y exfolian la piel muerta, dejando el cuerpo fresco. El exfoliante se enjuaga bajo la ducha Vichy, que a\u00f1ade un elemento de lujo, pues el agua caliente calma y aumenta la relajaci\u00f3n.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-35290\" src=\"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/01\/Banyan-Tree-Mayakoba-hydro-1.webp\" alt=\"\" width=\"450\" height=\"300\" srcset=\"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/01\/Banyan-Tree-Mayakoba-hydro-1.webp 450w, https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/01\/Banyan-Tree-Mayakoba-hydro-1-300x200.webp 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/p>\n<p>El viaje contin\u00faa en la tranquila sala de tratamientos con un masaje que integra t\u00e9cnicas de estiramiento tradicionales tailandesas, en las que terapeutas expertos utilizan sus conocimientos para aliviar la tensi\u00f3n y mejorar la flexibilidad. Estos estiramientos se combinan con un masaje con aceite que tambi\u00e9n incorpora compresas de hierbas tailandesas, calentados para liberar sus propiedades medicinales, proporcionando calor que penetra profundamente en los m\u00fasculos. Mediante una consulta detallada, el terapeuta se asegura de que el tratamiento se adapte a las necesidades de cada persona. A lo largo del tratamiento, el ambiente del spa incluye suaves sonidos de la naturaleza procedentes de los manglares y flujos de agua del exterior, lo que crea una tranquila inmersi\u00f3n en el entorno natural de la regi\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.banyantree.com\/es\/mexico\/mayakoba\" target=\"_blank\" rel=\"noopener\">www.banyantree.com\/es\/mexico\/mayakoba<\/a><\/p>\n<p>Por Sara Jones<br \/>\nEditora<\/p>\n<p><iframe title=\"BanyanTree Spa en Banyan Tree Mayakoba\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/l8VtPfzQG68?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enclavado en los exuberantes paisajes de la Riviera Maya, Banyan Tree Mayakoba ofrece un escape sereno que enfatiza relajaci\u00f3n y rejuvenecimiento, con el bienestar entretejido en las muchas actividades alrededor del resort. Con un excelente nivel de servicio en la propiedad y comida exquisita con extraordinaria atenci\u00f3n al detalle, los hu\u00e9spedes pueden asegurarse de que [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":35052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2190],"tags":[4721,4722,4723,2685,2729,2444,2430,4720,2506,2433],"class_list":["post-34973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","tag-banyan-tree-es","tag-banyan-tree-mayakoba-es","tag-banyan-tree-spa-es","tag-experiencia-spa-es","tag-hidroterapia-es","tag-masaje-es","tag-massage-es","tag-rainforest-indulgence","tag-sound-healing-es","tag-spa-experience-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Experiencia Spa: Banyan Tree Mayakoba<\/title>\n<meta name=\"description\" content=\"Banyan Tree Mayakoba ofrece un escape sereno que enfatiza relajaci\u00f3n, con el bienestar entretejido en muchas actividades del resort\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Experiencia Spa: Banyan Tree Mayakoba\" \/>\n<meta property=\"og:description\" content=\"Banyan Tree Mayakoba ofrece un escape sereno que enfatiza relajaci\u00f3n, con el bienestar entretejido en muchas actividades del resort\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/\" \/>\n<meta property=\"og:site_name\" content=\"Spa &amp; Wellness MexiCaribe\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-16T18:06:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-22T14:52:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/01\/Banyan-Tree-Mayakoba.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"766\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Fabiola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabiola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/34973\\\/experiencia-spa-banyan-tree-mayakoba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/34973\\\/experiencia-spa-banyan-tree-mayakoba\\\/\"},\"author\":{\"name\":\"Fabiola\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#\\\/schema\\\/person\\\/46d1b27e1e82f535658ced6aa4ebae47\"},\"headline\":\"Experiencia Spa: Banyan Tree Spa, Banyan Tree Mayakoba, Riviera Maya, M\u00e9xico\",\"datePublished\":\"2025-01-16T18:06:54+00:00\",\"dateModified\":\"2025-01-22T14:52:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/34973\\\/experiencia-spa-banyan-tree-mayakoba\\\/\"},\"wordCount\":512,\"publisher\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/34973\\\/experiencia-spa-banyan-tree-mayakoba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Banyan-Tree-Mayakoba.webp\",\"keywords\":[\"banyan tree\",\"banyan tree mayakoba\",\"banyan tree spa\",\"experiencia spa\",\"hidroterapia\",\"masaje\",\"massage\",\"rainforest indulgence\",\"sound healing\",\"spa experience\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/34973\\\/experiencia-spa-banyan-tree-mayakoba\\\/\",\"url\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/34973\\\/experiencia-spa-banyan-tree-mayakoba\\\/\",\"name\":\"Experiencia Spa: Banyan Tree Mayakoba\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/34973\\\/experiencia-spa-banyan-tree-mayakoba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/34973\\\/experiencia-spa-banyan-tree-mayakoba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Banyan-Tree-Mayakoba.webp\",\"datePublished\":\"2025-01-16T18:06:54+00:00\",\"dateModified\":\"2025-01-22T14:52:18+00:00\",\"description\":\"Banyan Tree Mayakoba ofrece un escape sereno que enfatiza relajaci\u00f3n, con el bienestar entretejido en muchas actividades del resort\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/34973\\\/experiencia-spa-banyan-tree-mayakoba\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/34973\\\/experiencia-spa-banyan-tree-mayakoba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/34973\\\/experiencia-spa-banyan-tree-mayakoba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Banyan-Tree-Mayakoba.webp\",\"contentUrl\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Banyan-Tree-Mayakoba.webp\",\"width\":766,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/blog-es\\\/34973\\\/experiencia-spa-banyan-tree-mayakoba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Experiencia Spa: Banyan Tree Spa, Banyan Tree Mayakoba, Riviera Maya, M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/\",\"name\":\"Spa &amp; Wellness MexiCaribe\",\"description\":\"The Magazine for Spa &amp; Wellness in Mexico, Caribbean &amp; Latin America\",\"publisher\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#organization\",\"name\":\"Spa &amp; Wellness MexiCaribe\",\"url\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cropped-LOGO-SWMC.png\",\"contentUrl\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cropped-LOGO-SWMC.png\",\"width\":1117,\"height\":230,\"caption\":\"Spa &amp; Wellness MexiCaribe\"},\"image\":{\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/es\\\/#\\\/schema\\\/person\\\/46d1b27e1e82f535658ced6aa4ebae47\",\"name\":\"Fabiola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/litespeed\\\/avatar\\\/9aea9838a8f24d3e63e9f38aa9599ebd.jpg?ver=1778538585&d=https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/plugins\\\/userswp\\\/assets\\\/images\\\/no_profile.png\",\"url\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/litespeed\\\/avatar\\\/9aea9838a8f24d3e63e9f38aa9599ebd.jpg?ver=1778538585&d=https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/plugins\\\/userswp\\\/assets\\\/images\\\/no_profile.png\",\"contentUrl\":\"https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/litespeed\\\/avatar\\\/9aea9838a8f24d3e63e9f38aa9599ebd.jpg?ver=1778538585&d=https:\\\/\\\/spawellnessmexico.com\\\/wp-content\\\/plugins\\\/userswp\\\/assets\\\/images\\\/no_profile.png\",\"caption\":\"Fabiola\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Experiencia Spa: Banyan Tree Mayakoba","description":"Banyan Tree Mayakoba ofrece un escape sereno que enfatiza relajaci\u00f3n, con el bienestar entretejido en muchas actividades del resort","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/","og_locale":"es_ES","og_type":"article","og_title":"Experiencia Spa: Banyan Tree Mayakoba","og_description":"Banyan Tree Mayakoba ofrece un escape sereno que enfatiza relajaci\u00f3n, con el bienestar entretejido en muchas actividades del resort","og_url":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/","og_site_name":"Spa &amp; Wellness MexiCaribe","article_published_time":"2025-01-16T18:06:54+00:00","article_modified_time":"2025-01-22T14:52:18+00:00","og_image":[{"width":766,"height":320,"url":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/01\/Banyan-Tree-Mayakoba.webp","type":"image\/webp"}],"author":"Fabiola","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fabiola","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/#article","isPartOf":{"@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/"},"author":{"name":"Fabiola","@id":"https:\/\/spawellnessmexico.com\/es\/#\/schema\/person\/46d1b27e1e82f535658ced6aa4ebae47"},"headline":"Experiencia Spa: Banyan Tree Spa, Banyan Tree Mayakoba, Riviera Maya, M\u00e9xico","datePublished":"2025-01-16T18:06:54+00:00","dateModified":"2025-01-22T14:52:18+00:00","mainEntityOfPage":{"@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/"},"wordCount":512,"publisher":{"@id":"https:\/\/spawellnessmexico.com\/es\/#organization"},"image":{"@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/#primaryimage"},"thumbnailUrl":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/01\/Banyan-Tree-Mayakoba.webp","keywords":["banyan tree","banyan tree mayakoba","banyan tree spa","experiencia spa","hidroterapia","masaje","massage","rainforest indulgence","sound healing","spa experience"],"articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/","url":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/","name":"Experiencia Spa: Banyan Tree Mayakoba","isPartOf":{"@id":"https:\/\/spawellnessmexico.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/#primaryimage"},"image":{"@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/#primaryimage"},"thumbnailUrl":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/01\/Banyan-Tree-Mayakoba.webp","datePublished":"2025-01-16T18:06:54+00:00","dateModified":"2025-01-22T14:52:18+00:00","description":"Banyan Tree Mayakoba ofrece un escape sereno que enfatiza relajaci\u00f3n, con el bienestar entretejido en muchas actividades del resort","breadcrumb":{"@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/#primaryimage","url":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/01\/Banyan-Tree-Mayakoba.webp","contentUrl":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2025\/01\/Banyan-Tree-Mayakoba.webp","width":766,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/spawellnessmexico.com\/es\/blog-es\/34973\/experiencia-spa-banyan-tree-mayakoba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spawellnessmexico.com\/es\/"},{"@type":"ListItem","position":2,"name":"Experiencia Spa: Banyan Tree Spa, Banyan Tree Mayakoba, Riviera Maya, M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/spawellnessmexico.com\/es\/#website","url":"https:\/\/spawellnessmexico.com\/es\/","name":"Spa &amp; Wellness MexiCaribe","description":"The Magazine for Spa &amp; Wellness in Mexico, Caribbean &amp; Latin America","publisher":{"@id":"https:\/\/spawellnessmexico.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spawellnessmexico.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/spawellnessmexico.com\/es\/#organization","name":"Spa &amp; Wellness MexiCaribe","url":"https:\/\/spawellnessmexico.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spawellnessmexico.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2021\/02\/cropped-LOGO-SWMC.png","contentUrl":"https:\/\/spawellnessmexico.com\/wp-content\/uploads\/2021\/02\/cropped-LOGO-SWMC.png","width":1117,"height":230,"caption":"Spa &amp; Wellness MexiCaribe"},"image":{"@id":"https:\/\/spawellnessmexico.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/spawellnessmexico.com\/es\/#\/schema\/person\/46d1b27e1e82f535658ced6aa4ebae47","name":"Fabiola","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spawellnessmexico.com\/wp-content\/litespeed\/avatar\/9aea9838a8f24d3e63e9f38aa9599ebd.jpg?ver=1778538585&d=https:\/\/spawellnessmexico.com\/wp-content\/plugins\/userswp\/assets\/images\/no_profile.png","url":"https:\/\/spawellnessmexico.com\/wp-content\/litespeed\/avatar\/9aea9838a8f24d3e63e9f38aa9599ebd.jpg?ver=1778538585&d=https:\/\/spawellnessmexico.com\/wp-content\/plugins\/userswp\/assets\/images\/no_profile.png","contentUrl":"https:\/\/spawellnessmexico.com\/wp-content\/litespeed\/avatar\/9aea9838a8f24d3e63e9f38aa9599ebd.jpg?ver=1778538585&d=https:\/\/spawellnessmexico.com\/wp-content\/plugins\/userswp\/assets\/images\/no_profile.png","caption":"Fabiola"}}]}},"_links":{"self":[{"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/posts\/34973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/comments?post=34973"}],"version-history":[{"count":3,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/posts\/34973\/revisions"}],"predecessor-version":[{"id":35295,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/posts\/34973\/revisions\/35295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/media\/35052"}],"wp:attachment":[{"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/media?parent=34973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/categories?post=34973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spawellnessmexico.com\/es\/wp-json\/wp\/v2\/tags?post=34973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}